{"id":10529,"date":"2024-12-31T11:33:10","date_gmt":"2024-12-31T11:33:10","guid":{"rendered":"https:\/\/acc.ueuromed.org\/2024\/12\/31\/pr-james-f-hollifield-a-luniversite-euromed-de-fes\/"},"modified":"2025-02-21T08:24:30","modified_gmt":"2025-02-21T08:24:30","slug":"pr-james-f-hollifield-a-luniversite-euromed-de-fes","status":"publish","type":"post","link":"https:\/\/acc.ueuromed.org\/en\/2024\/12\/31\/pr-james-f-hollifield-a-luniversite-euromed-de-fes\/","title":{"rendered":"Pr. James F. Hollifield \u00e0 l&#8217;Universit\u00e9 Euromed de F\u00e8s"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10529\" class=\"elementor elementor-10529\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1dac8007 e-flex e-con-boxed e-con e-parent\" data-id=\"1dac8007\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-43e265e e-con-full e-flex e-con e-child\" data-id=\"43e265e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67ecb20d exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"67ecb20d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">May 30, 2024<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67d46996 e-con-full e-flex e-con e-child\" data-id=\"67d46996\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a39b9c2 e-flex e-con-boxed e-con e-parent\" data-id=\"5a39b9c2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d7c48eb exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-heading\" data-id=\"1d7c48eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Pr. James F. Hollifield \u00e0 l'Universit\u00e9 Euromed de F\u00e8s :\n\n\"D\u00e9fi de la migration forc\u00e9e et du d\u00e9placement humain\"<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1dbbc40c e-flex e-con-boxed e-con e-parent\" data-id=\"1dbbc40c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7e9b2541 e-con-full e-flex e-con e-child\" data-id=\"7e9b2541\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1650148a exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"1650148a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/acc.ueuromed.org\/wp-content\/uploads\/2024\/12\/Pr.-James-F.-Hollifield-01-2-600x450.webp\" class=\"attachment-consultio-medium size-consultio-medium wp-image-8535\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6dcd0df6 e-con-full e-flex e-con e-child\" data-id=\"6dcd0df6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10324d44 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-image\" data-id=\"10324d44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"450\" src=\"https:\/\/acc.ueuromed.org\/wp-content\/uploads\/2024\/12\/Pr.-James-F.-Hollifield-02-1-600x450.webp\" class=\"attachment-consultio-medium size-consultio-medium wp-image-8536\" alt=\"\" srcset=\"https:\/\/acc.ueuromed.org\/wp-content\/uploads\/2024\/12\/Pr.-James-F.-Hollifield-02-1-600x450.webp 600w, https:\/\/acc.ueuromed.org\/wp-content\/uploads\/2024\/12\/Pr.-James-F.-Hollifield-02-1-300x225.webp 300w, https:\/\/acc.ueuromed.org\/wp-content\/uploads\/2024\/12\/Pr.-James-F.-Hollifield-02-1-1024x768.webp 1024w, https:\/\/acc.ueuromed.org\/wp-content\/uploads\/2024\/12\/Pr.-James-F.-Hollifield-02-1-768x576.webp 768w, https:\/\/acc.ueuromed.org\/wp-content\/uploads\/2024\/12\/Pr.-James-F.-Hollifield-02-1-1536x1152.webp 1536w, https:\/\/acc.ueuromed.org\/wp-content\/uploads\/2024\/12\/Pr.-James-F.-Hollifield-02-1.webp 1600w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13bbd794 e-flex e-con-boxed e-con e-parent\" data-id=\"13bbd794\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-717059f3 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-text-editor\" data-id=\"717059f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019Universit\u00e9 Euromed de F\u00e8s a accueilli, le 30 mai 2024, le Professeur James F. Hollifield qui a donn\u00e9 une conf\u00e9rence \u00e9clairante sur la gouvernance des migrations et les crises humanitaires mondiales. Membre \u00e9minent du Council on Foreign Relations (CFR) de New York et expert reconnu dans le domaine des migrations, le Professeur Hollifield a apport\u00e9 son expertise et ses insights sur la gouvernance des migrations.<\/p><p>Il est \u00e0 rappeler que M. Hollifield est titulaire de la Chaire \u00ab Ora Nixon Arnold en \u00e9conomie politique internationale \u00bb et Directeur du Tower Center de l\u2019Universit\u00e9 M\u00e9thodiste du Sud (SMU) \u00e0 Dallas, au Texas. Pr. Hollifield a consacr\u00e9 une grande partie de ses \u00e9crits aux questions li\u00e9es aux aspects du d\u00e9veloppement politique et \u00e9conomique, avec une attention particuli\u00e8re accord\u00e9e aux mouvements migratoires, et il a travaill\u00e9 comme conseiller aupr\u00e8s de diff\u00e9rents gouvernements en Am\u00e9rique du Nord et du Sud, en Europe, au Moyen-Orient et en Afrique. Il a \u00e9galement \u00e9t\u00e9 consultant aupr\u00e8s de nombreuses organisations internationales, notamment les Nations Unies, la Banque Mondiale, la Banque Interam\u00e9ricaine de D\u00e9veloppement, l&#8217;Union Europ\u00e9enne, l&#8217;OCDE et l&#8217;Organisation des \u00c9tats am\u00e9ricains.<\/p><p>Au cours de cette conf\u00e9rence, le Professeur Hollifield a partag\u00e9 ses r\u00e9flexions sur cette question pressante, offrant un aper\u00e7u \u00e9clair\u00e9 sur la crise humanitaire mondiale li\u00e9e \u00e0 la migration forc\u00e9e en abordant les questions li\u00e9es \u00e0 la complexit\u00e9 des politiques migratoires et aux dilemmes de la gouvernance et la gestion de ce ph\u00e9nom\u00e8ne social. Fort de son exp\u00e9rience en tant que conseiller aupr\u00e8s de gouvernements en Am\u00e9rique du Nord et du Sud, en Europe, au Moyen-Orient et en Afrique, ainsi que de sa contribution en tant que consultant pour diverses organisations internationales, M. Hollifield a apport\u00e9 une perspective unique et une expertise pr\u00e9cieuse \u00e0 cette discussion acad\u00e9mique.<\/p><p>&#8221; Les migrations forc\u00e9es continuent de se multiplier \u00e0 travers le monde, touchant des r\u00e9gions aussi diverses que les fronti\u00e8res marocaines, le sud-ouest des \u00c9tats-Unis et les c\u00f4tes m\u00e9diterran\u00e9ennes. Dans ce contexte, les \u00c9tats sont confront\u00e9s \u00e0 un d\u00e9fi complexe : comment \u00e9quilibrer leur imp\u00e9ratif s\u00e9curitaire avec leur devoir de prot\u00e9ger les droits humains des personnes d\u00e9plac\u00e9es, des demandeurs d&#8217;asile et des migrants en g\u00e9n\u00e9ral ?&#8221; a pr\u00e9cis\u00e9 M. Hollifield lors de cette rencontre.<\/p><p>Cette conf\u00e9rence a \u00e9t\u00e9 une opportunit\u00e9 unique pour nos \u00e9tudiants et nos enseignants chercheurs de comprendre les enjeux complexes li\u00e9s aux migrations forc\u00e9es et aux d\u00e9placements humains et aussi une occasion de promouvoir un dialogue constructif sur la mani\u00e8re dont les \u00c9tats peuvent r\u00e9pondre de mani\u00e8re efficace et \u00e9thique \u00e0 ces d\u00e9fis majeurs.<\/p><p>Cette rencontre, qui vient enrichir les Activit\u00e9s de la Chaire Alliance des Civilisations de l\u2019Universit\u00e9 Euromed de F\u00e8s, s\u2019inscrit dans le cadre d&#8217;une s\u00e9rie d\u2019\u00e9v\u00e8nements de grande ampleur tenus au sein de l\u2019UEMF visant \u00e0 renforcer la dynamique intellectuelle et stimuler la r\u00e9flexion des jeunes \u00e9tudiants de l\u2019Universit\u00e9 Euromed de F\u00e8s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36d99692 e-flex e-con-boxed e-con e-parent\" data-id=\"36d99692\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7dcb6d53 exad-sticky-section-no exad-glass-effect-no elementor-widget elementor-widget-ct_blog_grid\" data-id=\"7dcb6d53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ct_blog_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"ct_blog_grid-7dcb6d53\" class=\"ct-grid ct-blog-grid ct-blog-grid-layout4\" data-layout=\"masonry\" data-start-page=\"1\" data-max-pages=\"1\" data-total=\"4\" data-perpage=\"15\" data-next-link=\"\">\r\n    <div class=\"ct-grid-overlay\"><\/div>\r\n    \r\n    <div class=\"ct-grid-inner ct-grid-masonry row animate-time\" data-gutter=\"15\">\r\n                    <div class=\"grid-sizer col-xl-6 col-lg-6 col-md-4 col-sm-6 col-12\"><\/div>\r\n                                <div class=\"grid-item col-xl-6 col-lg-6 col-md-4 col-sm-6 col-12 filter-category-62\">\r\n                    <div class=\"grid-item-inner \">\r\n                                                    <div class=\"item--featured\">\r\n                                <a href=\"https:\/\/acc.ueuromed.org\/en\/2025\/11\/21\/thinking-the-state-in-the-age-of-global-shifts\/\"><img decoding=\"async\" class=\"disable-lazy no-lazyload \" src=\"https:\/\/acc.ueuromed.org\/wp-content\/uploads\/2025\/11\/Image-02-680x410.jpeg\" width=\"680\" height=\"410\" alt=\"Image 02\" title=\"Image 02\" \/><\/a>\r\n                            <\/div>\r\n                                                <div class=\"item--body\">\r\n                            <div class=\"item--holder\">\r\n                                                                    <ul class=\"item--meta\">\r\n                                                                                    <li class=\"item--date\"><i class=\"far fac-calendar-alt\"><\/i>21\/11\/2025<\/li>\r\n                                                                                                                            <li class=\"item--category\">\r\n                                                <i class=\"far fac-file-alt\"><\/i><a href=\"https:\/\/acc.ueuromed.org\/en\/category\/acc-conferences-en\/\" rel=\"tag\">ACC conferences<\/a>                                            <\/li>\r\n                                                                            <\/ul>\r\n                                                                <h3 class=\"item--title\"><a href=\"https:\/\/acc.ueuromed.org\/en\/2025\/11\/21\/thinking-the-state-in-the-age-of-global-shifts\/\">Thinking the State in the Age of Global Shifts<\/a><\/h3>\r\n                                                                    <div class=\"item--content\">\r\n                                                                            <\/div>\r\n                                                                                                    <div class=\"item--readmore\">\r\n                                        <a class=\"btn-text2\" href=\"https:\/\/acc.ueuromed.org\/en\/2025\/11\/21\/thinking-the-state-in-the-age-of-global-shifts\/\">\r\n                                            Lire la suite                                            <i class=\"flaticonv2 flaticonv2-right-arrow\"><\/i>\r\n                                        <\/a>\r\n                                    <\/div>\r\n                                                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                            <div class=\"grid-item col-xl-6 col-lg-6 col-md-4 col-sm-6 col-12 filter-category-62\">\r\n                    <div class=\"grid-item-inner \">\r\n                                                    <div class=\"item--featured\">\r\n                                <a href=\"https:\/\/acc.ueuromed.org\/en\/2025\/11\/19\/marche-de-larbitrage\/\"><img loading=\"lazy\" decoding=\"async\" class=\"disable-lazy no-lazyload \" src=\"https:\/\/acc.ueuromed.org\/wp-content\/uploads\/2025\/11\/DSC00269-scaled-680x410.jpeg\" width=\"680\" height=\"410\" alt=\"DSC00269\" title=\"DSC00269\" \/><\/a>\r\n                            <\/div>\r\n                                                <div class=\"item--body\">\r\n                            <div class=\"item--holder\">\r\n                                                                    <ul class=\"item--meta\">\r\n                                                                                    <li class=\"item--date\"><i class=\"far fac-calendar-alt\"><\/i>19\/11\/2025<\/li>\r\n                                                                                                                            <li class=\"item--category\">\r\n                                                <i class=\"far fac-file-alt\"><\/i><a href=\"https:\/\/acc.ueuromed.org\/en\/category\/acc-conferences-en\/\" rel=\"tag\">ACC conferences<\/a>                                            <\/li>\r\n                                                                            <\/ul>\r\n                                                                <h3 class=\"item--title\"><a href=\"https:\/\/acc.ueuromed.org\/en\/2025\/11\/19\/marche-de-larbitrage\/\">Pr Walid BEN HAMIDA sur la question du \u00ab march\u00e9 de l\u2019arbitrage \u00bb<\/a><\/h3>\r\n                                                                    <div class=\"item--content\">\r\n                                                                            <\/div>\r\n                                                                                                    <div class=\"item--readmore\">\r\n                                        <a class=\"btn-text2\" href=\"https:\/\/acc.ueuromed.org\/en\/2025\/11\/19\/marche-de-larbitrage\/\">\r\n                                            Lire la suite                                            <i class=\"flaticonv2 flaticonv2-right-arrow\"><\/i>\r\n                                        <\/a>\r\n                                    <\/div>\r\n                                                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                            <div class=\"grid-item col-xl-6 col-lg-6 col-md-4 col-sm-6 col-12 filter-category-62\">\r\n                    <div class=\"grid-item-inner \">\r\n                                                    <div class=\"item--featured\">\r\n                                <a href=\"https:\/\/acc.ueuromed.org\/en\/2024\/12\/31\/perspectives-des-zones-de-conflit\/\"><img loading=\"lazy\" decoding=\"async\" class=\"disable-lazy no-lazyload \" src=\"https:\/\/acc.ueuromed.org\/wp-content\/uploads\/2024\/12\/Fes-1photo_2023-12-09_08-08-05-1-680x410.jpg\" width=\"680\" height=\"410\" alt=\"Fes 1photo_2023-12-09_08-08-05\" title=\"Fes 1photo_2023-12-09_08-08-05\" \/><\/a>\r\n                            <\/div>\r\n                                                <div class=\"item--body\">\r\n                            <div class=\"item--holder\">\r\n                                                                    <ul class=\"item--meta\">\r\n                                                                                    <li class=\"item--date\"><i class=\"far fac-calendar-alt\"><\/i>31\/12\/2024<\/li>\r\n                                                                                                                            <li class=\"item--category\">\r\n                                                <i class=\"far fac-file-alt\"><\/i><a href=\"https:\/\/acc.ueuromed.org\/en\/category\/acc-conferences-en\/\" rel=\"tag\">ACC conferences<\/a>                                            <\/li>\r\n                                                                            <\/ul>\r\n                                                                <h3 class=\"item--title\"><a href=\"https:\/\/acc.ueuromed.org\/en\/2024\/12\/31\/perspectives-des-zones-de-conflit\/\">Perspectives des zones de conflit<\/a><\/h3>\r\n                                                                    <div class=\"item--content\">\r\n                                                                            <\/div>\r\n                                                                                                    <div class=\"item--readmore\">\r\n                                        <a class=\"btn-text2\" href=\"https:\/\/acc.ueuromed.org\/en\/2024\/12\/31\/perspectives-des-zones-de-conflit\/\">\r\n                                            Lire la suite                                            <i class=\"flaticonv2 flaticonv2-right-arrow\"><\/i>\r\n                                        <\/a>\r\n                                    <\/div>\r\n                                                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                            <div class=\"grid-item col-xl-6 col-lg-6 col-md-4 col-sm-6 col-12 filter-category-62\">\r\n                    <div class=\"grid-item-inner \">\r\n                                                    <div class=\"item--featured\">\r\n                                <a href=\"https:\/\/acc.ueuromed.org\/en\/2024\/12\/31\/prof-ghazi-gherairi\/\"><img loading=\"lazy\" decoding=\"async\" class=\"disable-lazy no-lazyload \" src=\"https:\/\/acc.ueuromed.org\/wp-content\/uploads\/2024\/12\/Prof.-Ghazi-Gherairi-03-1-680x410.webp\" width=\"680\" height=\"410\" alt=\"Prof. Ghazi Gherairi 03\" title=\"Prof. Ghazi Gherairi 03\" \/><\/a>\r\n                            <\/div>\r\n                                                <div class=\"item--body\">\r\n                            <div class=\"item--holder\">\r\n                                                                    <ul class=\"item--meta\">\r\n                                                                                    <li class=\"item--date\"><i class=\"far fac-calendar-alt\"><\/i>31\/12\/2024<\/li>\r\n                                                                                                                            <li class=\"item--category\">\r\n                                                <i class=\"far fac-file-alt\"><\/i><a href=\"https:\/\/acc.ueuromed.org\/en\/category\/acc-conferences-en\/\" rel=\"tag\">ACC conferences<\/a>                                            <\/li>\r\n                                                                            <\/ul>\r\n                                                                <h3 class=\"item--title\"><a href=\"https:\/\/acc.ueuromed.org\/en\/2024\/12\/31\/prof-ghazi-gherairi\/\">Quelles alliances pour quel monde en 2024 ?<\/a><\/h3>\r\n                                                                    <div class=\"item--content\">\r\n                                                                            <\/div>\r\n                                                                                                    <div class=\"item--readmore\">\r\n                                        <a class=\"btn-text2\" href=\"https:\/\/acc.ueuromed.org\/en\/2024\/12\/31\/prof-ghazi-gherairi\/\">\r\n                                            Lire la suite                                            <i class=\"flaticonv2 flaticonv2-right-arrow\"><\/i>\r\n                                        <\/a>\r\n                                    <\/div>\r\n                                                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                <\/div>\r\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>May 30, 2024 Pr. James F. Hollifield \u00e0 l&#8217;Universit\u00e9 Euromed de F\u00e8s : &#8220;D\u00e9fi de la migration forc\u00e9e et du d\u00e9placement humain&#8221; L\u2019Universit\u00e9 Euromed de F\u00e8s a accueilli, le 30 mai 2024, le Professeur James F. Hollifield qui a donn\u00e9 une conf\u00e9rence \u00e9clairante sur la gouvernance des migrations et les crises humanitaires mondiales. Membre \u00e9minent [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10530,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"postBodyCss":"","postBodyMargin":[],"postBodyPadding":[],"postBodyBackground":{"backgroundType":"classic","gradient":""},"cybocfi_hide_featured_image":"yes","footnotes":""},"categories":[62],"tags":[],"class_list":["post-10529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acc-conferences-en"],"_links":{"self":[{"href":"https:\/\/acc.ueuromed.org\/en\/wp-json\/wp\/v2\/posts\/10529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acc.ueuromed.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acc.ueuromed.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acc.ueuromed.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acc.ueuromed.org\/en\/wp-json\/wp\/v2\/comments?post=10529"}],"version-history":[{"count":1,"href":"https:\/\/acc.ueuromed.org\/en\/wp-json\/wp\/v2\/posts\/10529\/revisions"}],"predecessor-version":[{"id":10531,"href":"https:\/\/acc.ueuromed.org\/en\/wp-json\/wp\/v2\/posts\/10529\/revisions\/10531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acc.ueuromed.org\/en\/wp-json\/wp\/v2\/media\/10530"}],"wp:attachment":[{"href":"https:\/\/acc.ueuromed.org\/en\/wp-json\/wp\/v2\/media?parent=10529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acc.ueuromed.org\/en\/wp-json\/wp\/v2\/categories?post=10529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acc.ueuromed.org\/en\/wp-json\/wp\/v2\/tags?post=10529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}